{"id":21198,"date":"2023-06-20T00:00:00","date_gmt":"2023-06-20T00:00:00","guid":{"rendered":"https:\/\/ibgw-leipzig.de\/?post_type=projects&amp;p=21198"},"modified":"2023-06-20T00:00:00","modified_gmt":"2023-06-20T00:00:00","slug":"orientierende-untersuchung-phase-iia-der-standortschiesanlage-bad-arolsen-bad-arolsen","status":"publish","type":"projects","link":"https:\/\/tucherundpartner.de\/en\/projects\/orientierende-untersuchung-phase-iia-der-standortschiesanlage-bad-arolsen-bad-arolsen\/","title":{"rendered":"Orienting investigation (Phase IIa) of the Bad Arolsen site shooting range, Bad Arolsen"},"content":{"rendered":"<figure class=\"wp-block-table\"><table><tbody><tr><td>Period:<\/td><td>2020<\/td><\/tr><tr><td>Field of activity:<\/td><td>Orienting examination<\/td><\/tr><tr><td>Scope of services:<\/td><td>Orienting investigation according to the Building Guidelines for Soil and Groundwater Protection (BFR BoGWS)<\/td><\/tr><tr><td>Short description:<\/td><td>The commissioned scope of services included investigations in accordance with the construction guidelines for soil and groundwater protection for phase IIa (orienting investigation).A business unit (BU) with five different suspected contamination areas, which were identified in the previous phase I, was considered. The target\/bullet trap areas of the individual firing ranges represent the suspected contamination areas.The WE was used by the German Federal Armed Forces as a firing range between 1964 and 1997. Before that, the area was used for agriculture. In 2002, the site was handed over to the Bundesanstalt f\u00fcr Immobilienaufgaben (Federal Agency for Real Estate Tasks) and now examined for harmful soil changes in the course of a planned restitution measure.The aim of the orienting investigation was to examine possible contamination under consideration of the impact pathway soil-human. Within the framework of the project, orienting investigations of the topsoil of the shooting range areas were carried out, among other things. In order to obtain a reliable statement as to whether projectile residues may be found in the mounds, these were examined by means of trenching. The results of the investigations and the chemical analyses were documented and evaluated in an expert report. A risk assessment was carried out with regard to the soil-human impact pathway and recommendations for measures were formulated.<\/td><\/tr><\/tbody><\/table><\/figure>","protected":false},"author":49,"featured_media":0,"parent":0,"template":"","company-group":[],"project-category":[57],"class_list":["post-21198","projects","type-projects","status-publish","hentry","project-category-boden"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"robots\" content=\"noindex, max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Syed Aatik Ahmed\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/tucherundpartner.de\/en\/projects\/orientierende-untersuchung-phase-iia-der-standortschiesanlage-bad-arolsen-bad-arolsen\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_GB\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Tucher Ingenieure GmbH - Engineering for a better tomorrow\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Orientierende Untersuchung (Phase IIa) der Standortschie\u00dfanlage Bad Arolsen, Bad Arolsen - Tucher Ingenieure GmbH\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/tucherundpartner.de\/en\/projects\/orientierende-untersuchung-phase-iia-der-standortschiesanlage-bad-arolsen-bad-arolsen\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-06-20T00:00:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-06-20T00:00:00+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Orientierende Untersuchung (Phase IIa) der Standortschie\u00dfanlage Bad Arolsen, Bad Arolsen - Tucher Ingenieure GmbH\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/projects\\\/orientierende-untersuchung-phase-iia-der-standortschiesanlage-bad-arolsen-bad-arolsen\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tucherundpartner.de\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/projects\\\/#listItem\",\"name\":\"Projects\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/projects\\\/#listItem\",\"position\":2,\"name\":\"Projects\",\"item\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/projects\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/project-category\\\/boden\\\/#listItem\",\"name\":\"Boden\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/project-category\\\/boden\\\/#listItem\",\"position\":3,\"name\":\"Boden\",\"item\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/project-category\\\/boden\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/projects\\\/orientierende-untersuchung-phase-iia-der-standortschiesanlage-bad-arolsen-bad-arolsen\\\/#listItem\",\"name\":\"Orientierende Untersuchung (Phase IIa) der Standortschie\\u00dfanlage Bad Arolsen, Bad Arolsen\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/projects\\\/#listItem\",\"name\":\"Projects\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/projects\\\/orientierende-untersuchung-phase-iia-der-standortschiesanlage-bad-arolsen-bad-arolsen\\\/#listItem\",\"position\":4,\"name\":\"Orientierende Untersuchung (Phase IIa) der Standortschie\\u00dfanlage Bad Arolsen, Bad Arolsen\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/project-category\\\/boden\\\/#listItem\",\"name\":\"Boden\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/#organization\",\"name\":\"Tucher Ingenieure GmbH\",\"description\":\"Engineering for a better tomorrow\",\"url\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/author\\\/syed-aatik-ahmedsiera-com\\\/#author\",\"url\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/author\\\/syed-aatik-ahmedsiera-com\\\/\",\"name\":\"Syed Aatik Ahmed\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/projects\\\/orientierende-untersuchung-phase-iia-der-standortschiesanlage-bad-arolsen-bad-arolsen\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f49dc8cc038d949451508ccb8969e6c28473b086098250589970017b228e0bdd?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Syed Aatik Ahmed\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/projects\\\/orientierende-untersuchung-phase-iia-der-standortschiesanlage-bad-arolsen-bad-arolsen\\\/#webpage\",\"url\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/projects\\\/orientierende-untersuchung-phase-iia-der-standortschiesanlage-bad-arolsen-bad-arolsen\\\/\",\"name\":\"Orientierende Untersuchung (Phase IIa) der Standortschie\\u00dfanlage Bad Arolsen, Bad Arolsen - Tucher Ingenieure GmbH\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/projects\\\/orientierende-untersuchung-phase-iia-der-standortschiesanlage-bad-arolsen-bad-arolsen\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/author\\\/syed-aatik-ahmedsiera-com\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/author\\\/syed-aatik-ahmedsiera-com\\\/#author\"},\"datePublished\":\"2023-06-20T00:00:00+00:00\",\"dateModified\":\"2023-06-20T00:00:00+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/\",\"name\":\"Tucher Ingenieure GmbH\",\"description\":\"Engineering for a better tomorrow\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Orientierende Untersuchung (Phase IIa) der Standortschie\u00dfanlage Bad Arolsen, Bad Arolsen - Tucher Ingenieure GmbH","description":"","canonical_url":"https:\/\/tucherundpartner.de\/en\/projects\/orientierende-untersuchung-phase-iia-der-standortschiesanlage-bad-arolsen-bad-arolsen\/","robots":"noindex, max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/tucherundpartner.de\/en\/projects\/orientierende-untersuchung-phase-iia-der-standortschiesanlage-bad-arolsen-bad-arolsen\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/tucherundpartner.de\/en#listItem","position":1,"name":"Home","item":"https:\/\/tucherundpartner.de\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/tucherundpartner.de\/en\/projects\/#listItem","name":"Projects"}},{"@type":"ListItem","@id":"https:\/\/tucherundpartner.de\/en\/projects\/#listItem","position":2,"name":"Projects","item":"https:\/\/tucherundpartner.de\/en\/projects\/","nextItem":{"@type":"ListItem","@id":"https:\/\/tucherundpartner.de\/en\/project-category\/boden\/#listItem","name":"Boden"},"previousItem":{"@type":"ListItem","@id":"https:\/\/tucherundpartner.de\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/tucherundpartner.de\/en\/project-category\/boden\/#listItem","position":3,"name":"Boden","item":"https:\/\/tucherundpartner.de\/en\/project-category\/boden\/","nextItem":{"@type":"ListItem","@id":"https:\/\/tucherundpartner.de\/en\/projects\/orientierende-untersuchung-phase-iia-der-standortschiesanlage-bad-arolsen-bad-arolsen\/#listItem","name":"Orientierende Untersuchung (Phase IIa) der Standortschie\u00dfanlage Bad Arolsen, Bad Arolsen"},"previousItem":{"@type":"ListItem","@id":"https:\/\/tucherundpartner.de\/en\/projects\/#listItem","name":"Projects"}},{"@type":"ListItem","@id":"https:\/\/tucherundpartner.de\/en\/projects\/orientierende-untersuchung-phase-iia-der-standortschiesanlage-bad-arolsen-bad-arolsen\/#listItem","position":4,"name":"Orientierende Untersuchung (Phase IIa) der Standortschie\u00dfanlage Bad Arolsen, Bad Arolsen","previousItem":{"@type":"ListItem","@id":"https:\/\/tucherundpartner.de\/en\/project-category\/boden\/#listItem","name":"Boden"}}]},{"@type":"Organization","@id":"https:\/\/tucherundpartner.de\/en\/#organization","name":"Tucher Ingenieure GmbH","description":"Engineering for a better tomorrow","url":"https:\/\/tucherundpartner.de\/en\/"},{"@type":"Person","@id":"https:\/\/tucherundpartner.de\/en\/author\/syed-aatik-ahmedsiera-com\/#author","url":"https:\/\/tucherundpartner.de\/en\/author\/syed-aatik-ahmedsiera-com\/","name":"Syed Aatik Ahmed","image":{"@type":"ImageObject","@id":"https:\/\/tucherundpartner.de\/en\/projects\/orientierende-untersuchung-phase-iia-der-standortschiesanlage-bad-arolsen-bad-arolsen\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/f49dc8cc038d949451508ccb8969e6c28473b086098250589970017b228e0bdd?s=96&d=mm&r=g","width":96,"height":96,"caption":"Syed Aatik Ahmed"}},{"@type":"WebPage","@id":"https:\/\/tucherundpartner.de\/en\/projects\/orientierende-untersuchung-phase-iia-der-standortschiesanlage-bad-arolsen-bad-arolsen\/#webpage","url":"https:\/\/tucherundpartner.de\/en\/projects\/orientierende-untersuchung-phase-iia-der-standortschiesanlage-bad-arolsen-bad-arolsen\/","name":"Orientierende Untersuchung (Phase IIa) der Standortschie\u00dfanlage Bad Arolsen, Bad Arolsen - Tucher Ingenieure GmbH","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/tucherundpartner.de\/en\/#website"},"breadcrumb":{"@id":"https:\/\/tucherundpartner.de\/en\/projects\/orientierende-untersuchung-phase-iia-der-standortschiesanlage-bad-arolsen-bad-arolsen\/#breadcrumblist"},"author":{"@id":"https:\/\/tucherundpartner.de\/en\/author\/syed-aatik-ahmedsiera-com\/#author"},"creator":{"@id":"https:\/\/tucherundpartner.de\/en\/author\/syed-aatik-ahmedsiera-com\/#author"},"datePublished":"2023-06-20T00:00:00+00:00","dateModified":"2023-06-20T00:00:00+00:00"},{"@type":"WebSite","@id":"https:\/\/tucherundpartner.de\/en\/#website","url":"https:\/\/tucherundpartner.de\/en\/","name":"Tucher Ingenieure GmbH","description":"Engineering for a better tomorrow","inLanguage":"en-GB","publisher":{"@id":"https:\/\/tucherundpartner.de\/en\/#organization"}}]},"og:locale":"en_GB","og:site_name":"Tucher Ingenieure GmbH - Engineering for a better tomorrow","og:type":"article","og:title":"Orientierende Untersuchung (Phase IIa) der Standortschie\u00dfanlage Bad Arolsen, Bad Arolsen - Tucher Ingenieure GmbH","og:url":"https:\/\/tucherundpartner.de\/en\/projects\/orientierende-untersuchung-phase-iia-der-standortschiesanlage-bad-arolsen-bad-arolsen\/","article:published_time":"2023-06-20T00:00:00+00:00","article:modified_time":"2023-06-20T00:00:00+00:00","twitter:card":"summary_large_image","twitter:title":"Orientierende Untersuchung (Phase IIa) der Standortschie\u00dfanlage Bad Arolsen, Bad Arolsen - Tucher Ingenieure GmbH"},"aioseo_meta_data":{"post_id":"21198","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-10-29 08:04:09","updated":"2025-10-29 08:04:09","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/tucherundpartner.de\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/tucherundpartner.de\/en\/projects\/\" title=\"Projects\">Projects<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/tucherundpartner.de\/en\/project-category\/boden\/\" title=\"Boden\">Boden<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tOrientierende Untersuchung (Phase IIa) der Standortschie\u00dfanlage Bad Arolsen, Bad Arolsen\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/tucherundpartner.de\/en"},{"label":"Projects","link":"https:\/\/tucherundpartner.de\/en\/projects\/"},{"label":"Boden","link":"https:\/\/tucherundpartner.de\/en\/project-category\/boden\/"},{"label":"Orientierende Untersuchung (Phase IIa) der Standortschie\u00dfanlage Bad Arolsen, Bad Arolsen","link":"https:\/\/tucherundpartner.de\/en\/projects\/orientierende-untersuchung-phase-iia-der-standortschiesanlage-bad-arolsen-bad-arolsen\/"}],"_links":{"self":[{"href":"https:\/\/tucherundpartner.de\/en\/wp-json\/wp\/v2\/projects\/21198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tucherundpartner.de\/en\/wp-json\/wp\/v2\/projects"}],"about":[{"href":"https:\/\/tucherundpartner.de\/en\/wp-json\/wp\/v2\/types\/projects"}],"author":[{"embeddable":true,"href":"https:\/\/tucherundpartner.de\/en\/wp-json\/wp\/v2\/users\/49"}],"wp:attachment":[{"href":"https:\/\/tucherundpartner.de\/en\/wp-json\/wp\/v2\/media?parent=21198"}],"wp:term":[{"taxonomy":"company-group","embeddable":true,"href":"https:\/\/tucherundpartner.de\/en\/wp-json\/wp\/v2\/company-group?post=21198"},{"taxonomy":"project-category","embeddable":true,"href":"https:\/\/tucherundpartner.de\/en\/wp-json\/wp\/v2\/project-category?post=21198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}