{"id":21084,"date":"2023-06-15T00:00:00","date_gmt":"2023-06-15T00:00:00","guid":{"rendered":"https:\/\/ibgw-leipzig.de\/?post_type=projects&amp;p=21084"},"modified":"2023-06-15T00:00:00","modified_gmt":"2023-06-15T00:00:00","slug":"environmental-due-diligence-quick-check-fur-eine-flachenentwicklung-bei-hamburg","status":"publish","type":"projects","link":"https:\/\/tucherundpartner.de\/en\/projects\/environmental-due-diligence-quick-check-fur-eine-flachenentwicklung-bei-hamburg\/","title":{"rendered":"Environmental due diligence (\"quick check\") for a land development near Hamburg"},"content":{"rendered":"<ul class=\"wp-block-list\">\n<li>Project description: In the context of a planned land acquisition of a former industrial site, the site-related framework conditions were to be examined.<\/li>\n\n\n\n<li>Our services: Preparation of a desktop study (\"quick check\") to examine the site-related framework conditions with regard to planning law, geotechnics, contaminated sites, explosive ordnance, nature conservation and species protection, supply and disposal, traffic and noise; advising the client with regard to necessary further investigations (building pollutant investigation, subsoil and contaminated site investigation, species protection potential analysis and mapping, drainage concept); coordination of the necessary expert opinions via the corresponding specialist departments of the M&amp;P Group and external subcontractors.<\/li>\n\n\n\n<li>Duration: 2021 - 2022<\/li>\n\n\n\n<li>Industry of the client: Real estate developer in the logistics industry<\/li>\n<\/ul>","protected":false},"author":49,"featured_media":0,"parent":0,"template":"","company-group":[],"project-category":[55],"class_list":["post-21084","projects","type-projects","status-publish","hentry","project-category-umwelt"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"Projektbeschreibung: Im Rahmen eines geplanten Grundst\u00fccksankaufs eines ehemaligen Industriestandorts sollten die standortbezogenen Rahmenbedingungen gepr\u00fcft werden. Unsere Leistungen: Erarbeitung einer Desktop-Studie (\u201eQuick-Check\u201c) zur Pr\u00fcfung der standortbezogenen Rahmenbedingungen bzgl. Planungsrecht, Geotechnik, Altlasten, Kampfmittel, Natur- und Artenschutz, Ver- und Entsorgung, Verkehr und Schall; Beratung des Kunden in Hinblick auf notwendige weiterf\u00fchrende Untersuchungen (Geb\u00e4udeschadstoffuntersuchung, Baugrund- und Altlastenuntersuchung, Artenschutz-Potenzialanalyse und\" \/>\n\t<meta name=\"robots\" content=\"noindex, max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Syed Aatik Ahmed\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/tucherundpartner.de\/en\/projects\/environmental-due-diligence-quick-check-fur-eine-flachenentwicklung-bei-hamburg\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_GB\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Tucher Ingenieure GmbH - Engineering for a better tomorrow\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Environmental Due Diligence (\u201eQuick-Check\u201c) f\u00fcr eine Fl\u00e4chenentwicklung bei Hamburg - Tucher Ingenieure GmbH\" \/>\n\t\t<meta property=\"og:description\" content=\"Projektbeschreibung: Im Rahmen eines geplanten Grundst\u00fccksankaufs eines ehemaligen Industriestandorts sollten die standortbezogenen Rahmenbedingungen gepr\u00fcft werden. Unsere Leistungen: Erarbeitung einer Desktop-Studie (\u201eQuick-Check\u201c) zur Pr\u00fcfung der standortbezogenen Rahmenbedingungen bzgl. Planungsrecht, Geotechnik, Altlasten, Kampfmittel, Natur- und Artenschutz, Ver- und Entsorgung, Verkehr und Schall; Beratung des Kunden in Hinblick auf notwendige weiterf\u00fchrende Untersuchungen (Geb\u00e4udeschadstoffuntersuchung, Baugrund- und Altlastenuntersuchung, Artenschutz-Potenzialanalyse und\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/tucherundpartner.de\/en\/projects\/environmental-due-diligence-quick-check-fur-eine-flachenentwicklung-bei-hamburg\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-06-15T00:00:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-06-15T00:00:00+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Environmental Due Diligence (\u201eQuick-Check\u201c) f\u00fcr eine Fl\u00e4chenentwicklung bei Hamburg - Tucher Ingenieure GmbH\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Projektbeschreibung: Im Rahmen eines geplanten Grundst\u00fccksankaufs eines ehemaligen Industriestandorts sollten die standortbezogenen Rahmenbedingungen gepr\u00fcft werden. Unsere Leistungen: Erarbeitung einer Desktop-Studie (\u201eQuick-Check\u201c) zur Pr\u00fcfung der standortbezogenen Rahmenbedingungen bzgl. Planungsrecht, Geotechnik, Altlasten, Kampfmittel, Natur- und Artenschutz, Ver- und Entsorgung, Verkehr und Schall; Beratung des Kunden in Hinblick auf notwendige weiterf\u00fchrende Untersuchungen (Geb\u00e4udeschadstoffuntersuchung, Baugrund- und Altlastenuntersuchung, Artenschutz-Potenzialanalyse und\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/projects\\\/environmental-due-diligence-quick-check-fur-eine-flachenentwicklung-bei-hamburg\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tucherundpartner.de\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/projects\\\/#listItem\",\"name\":\"Projects\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/projects\\\/#listItem\",\"position\":2,\"name\":\"Projects\",\"item\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/projects\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/project-category\\\/umwelt\\\/#listItem\",\"name\":\"Umwelt\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/project-category\\\/umwelt\\\/#listItem\",\"position\":3,\"name\":\"Umwelt\",\"item\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/project-category\\\/umwelt\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/projects\\\/environmental-due-diligence-quick-check-fur-eine-flachenentwicklung-bei-hamburg\\\/#listItem\",\"name\":\"Environmental Due Diligence (\\u201eQuick-Check\\u201c) f\\u00fcr eine Fl\\u00e4chenentwicklung bei Hamburg\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/projects\\\/#listItem\",\"name\":\"Projects\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/projects\\\/environmental-due-diligence-quick-check-fur-eine-flachenentwicklung-bei-hamburg\\\/#listItem\",\"position\":4,\"name\":\"Environmental Due Diligence (\\u201eQuick-Check\\u201c) f\\u00fcr eine Fl\\u00e4chenentwicklung bei Hamburg\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/project-category\\\/umwelt\\\/#listItem\",\"name\":\"Umwelt\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/#organization\",\"name\":\"Tucher Ingenieure GmbH\",\"description\":\"Engineering for a better tomorrow\",\"url\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/author\\\/syed-aatik-ahmedsiera-com\\\/#author\",\"url\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/author\\\/syed-aatik-ahmedsiera-com\\\/\",\"name\":\"Syed Aatik Ahmed\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/projects\\\/environmental-due-diligence-quick-check-fur-eine-flachenentwicklung-bei-hamburg\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f49dc8cc038d949451508ccb8969e6c28473b086098250589970017b228e0bdd?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Syed Aatik Ahmed\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/projects\\\/environmental-due-diligence-quick-check-fur-eine-flachenentwicklung-bei-hamburg\\\/#webpage\",\"url\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/projects\\\/environmental-due-diligence-quick-check-fur-eine-flachenentwicklung-bei-hamburg\\\/\",\"name\":\"Environmental Due Diligence (\\u201eQuick-Check\\u201c) f\\u00fcr eine Fl\\u00e4chenentwicklung bei Hamburg - Tucher Ingenieure GmbH\",\"description\":\"Projektbeschreibung: Im Rahmen eines geplanten Grundst\\u00fccksankaufs eines ehemaligen Industriestandorts sollten die standortbezogenen Rahmenbedingungen gepr\\u00fcft werden. Unsere Leistungen: Erarbeitung einer Desktop-Studie (\\u201eQuick-Check\\u201c) zur Pr\\u00fcfung der standortbezogenen Rahmenbedingungen bzgl. Planungsrecht, Geotechnik, Altlasten, Kampfmittel, Natur- und Artenschutz, Ver- und Entsorgung, Verkehr und Schall; Beratung des Kunden in Hinblick auf notwendige weiterf\\u00fchrende Untersuchungen (Geb\\u00e4udeschadstoffuntersuchung, Baugrund- und Altlastenuntersuchung, Artenschutz-Potenzialanalyse und\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/projects\\\/environmental-due-diligence-quick-check-fur-eine-flachenentwicklung-bei-hamburg\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/author\\\/syed-aatik-ahmedsiera-com\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/author\\\/syed-aatik-ahmedsiera-com\\\/#author\"},\"datePublished\":\"2023-06-15T00:00:00+00:00\",\"dateModified\":\"2023-06-15T00:00:00+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/\",\"name\":\"Tucher Ingenieure GmbH\",\"description\":\"Engineering for a better tomorrow\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/tucherundpartner.de\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Environmental Due Diligence (\u201eQuick-Check\u201c) f\u00fcr eine Fl\u00e4chenentwicklung bei Hamburg - Tucher Ingenieure GmbH","description":"Projektbeschreibung: Im Rahmen eines geplanten Grundst\u00fccksankaufs eines ehemaligen Industriestandorts sollten die standortbezogenen Rahmenbedingungen gepr\u00fcft werden. Unsere Leistungen: Erarbeitung einer Desktop-Studie (\u201eQuick-Check\u201c) zur Pr\u00fcfung der standortbezogenen Rahmenbedingungen bzgl. Planungsrecht, Geotechnik, Altlasten, Kampfmittel, Natur- und Artenschutz, Ver- und Entsorgung, Verkehr und Schall; Beratung des Kunden in Hinblick auf notwendige weiterf\u00fchrende Untersuchungen (Geb\u00e4udeschadstoffuntersuchung, Baugrund- und Altlastenuntersuchung, Artenschutz-Potenzialanalyse und","canonical_url":"https:\/\/tucherundpartner.de\/en\/projects\/environmental-due-diligence-quick-check-fur-eine-flachenentwicklung-bei-hamburg\/","robots":"noindex, max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/tucherundpartner.de\/en\/projects\/environmental-due-diligence-quick-check-fur-eine-flachenentwicklung-bei-hamburg\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/tucherundpartner.de\/en#listItem","position":1,"name":"Home","item":"https:\/\/tucherundpartner.de\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/tucherundpartner.de\/en\/projects\/#listItem","name":"Projects"}},{"@type":"ListItem","@id":"https:\/\/tucherundpartner.de\/en\/projects\/#listItem","position":2,"name":"Projects","item":"https:\/\/tucherundpartner.de\/en\/projects\/","nextItem":{"@type":"ListItem","@id":"https:\/\/tucherundpartner.de\/en\/project-category\/umwelt\/#listItem","name":"Umwelt"},"previousItem":{"@type":"ListItem","@id":"https:\/\/tucherundpartner.de\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/tucherundpartner.de\/en\/project-category\/umwelt\/#listItem","position":3,"name":"Umwelt","item":"https:\/\/tucherundpartner.de\/en\/project-category\/umwelt\/","nextItem":{"@type":"ListItem","@id":"https:\/\/tucherundpartner.de\/en\/projects\/environmental-due-diligence-quick-check-fur-eine-flachenentwicklung-bei-hamburg\/#listItem","name":"Environmental Due Diligence (\u201eQuick-Check\u201c) f\u00fcr eine Fl\u00e4chenentwicklung bei Hamburg"},"previousItem":{"@type":"ListItem","@id":"https:\/\/tucherundpartner.de\/en\/projects\/#listItem","name":"Projects"}},{"@type":"ListItem","@id":"https:\/\/tucherundpartner.de\/en\/projects\/environmental-due-diligence-quick-check-fur-eine-flachenentwicklung-bei-hamburg\/#listItem","position":4,"name":"Environmental Due Diligence (\u201eQuick-Check\u201c) f\u00fcr eine Fl\u00e4chenentwicklung bei Hamburg","previousItem":{"@type":"ListItem","@id":"https:\/\/tucherundpartner.de\/en\/project-category\/umwelt\/#listItem","name":"Umwelt"}}]},{"@type":"Organization","@id":"https:\/\/tucherundpartner.de\/en\/#organization","name":"Tucher Ingenieure GmbH","description":"Engineering for a better tomorrow","url":"https:\/\/tucherundpartner.de\/en\/"},{"@type":"Person","@id":"https:\/\/tucherundpartner.de\/en\/author\/syed-aatik-ahmedsiera-com\/#author","url":"https:\/\/tucherundpartner.de\/en\/author\/syed-aatik-ahmedsiera-com\/","name":"Syed Aatik Ahmed","image":{"@type":"ImageObject","@id":"https:\/\/tucherundpartner.de\/en\/projects\/environmental-due-diligence-quick-check-fur-eine-flachenentwicklung-bei-hamburg\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/f49dc8cc038d949451508ccb8969e6c28473b086098250589970017b228e0bdd?s=96&d=mm&r=g","width":96,"height":96,"caption":"Syed Aatik Ahmed"}},{"@type":"WebPage","@id":"https:\/\/tucherundpartner.de\/en\/projects\/environmental-due-diligence-quick-check-fur-eine-flachenentwicklung-bei-hamburg\/#webpage","url":"https:\/\/tucherundpartner.de\/en\/projects\/environmental-due-diligence-quick-check-fur-eine-flachenentwicklung-bei-hamburg\/","name":"Environmental Due Diligence (\u201eQuick-Check\u201c) f\u00fcr eine Fl\u00e4chenentwicklung bei Hamburg - Tucher Ingenieure GmbH","description":"Projektbeschreibung: Im Rahmen eines geplanten Grundst\u00fccksankaufs eines ehemaligen Industriestandorts sollten die standortbezogenen Rahmenbedingungen gepr\u00fcft werden. Unsere Leistungen: Erarbeitung einer Desktop-Studie (\u201eQuick-Check\u201c) zur Pr\u00fcfung der standortbezogenen Rahmenbedingungen bzgl. Planungsrecht, Geotechnik, Altlasten, Kampfmittel, Natur- und Artenschutz, Ver- und Entsorgung, Verkehr und Schall; Beratung des Kunden in Hinblick auf notwendige weiterf\u00fchrende Untersuchungen (Geb\u00e4udeschadstoffuntersuchung, Baugrund- und Altlastenuntersuchung, Artenschutz-Potenzialanalyse und","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/tucherundpartner.de\/en\/#website"},"breadcrumb":{"@id":"https:\/\/tucherundpartner.de\/en\/projects\/environmental-due-diligence-quick-check-fur-eine-flachenentwicklung-bei-hamburg\/#breadcrumblist"},"author":{"@id":"https:\/\/tucherundpartner.de\/en\/author\/syed-aatik-ahmedsiera-com\/#author"},"creator":{"@id":"https:\/\/tucherundpartner.de\/en\/author\/syed-aatik-ahmedsiera-com\/#author"},"datePublished":"2023-06-15T00:00:00+00:00","dateModified":"2023-06-15T00:00:00+00:00"},{"@type":"WebSite","@id":"https:\/\/tucherundpartner.de\/en\/#website","url":"https:\/\/tucherundpartner.de\/en\/","name":"Tucher Ingenieure GmbH","description":"Engineering for a better tomorrow","inLanguage":"en-GB","publisher":{"@id":"https:\/\/tucherundpartner.de\/en\/#organization"}}]},"og:locale":"en_GB","og:site_name":"Tucher Ingenieure GmbH - Engineering for a better tomorrow","og:type":"article","og:title":"Environmental Due Diligence (\u201eQuick-Check\u201c) f\u00fcr eine Fl\u00e4chenentwicklung bei Hamburg - Tucher Ingenieure GmbH","og:description":"Projektbeschreibung: Im Rahmen eines geplanten Grundst\u00fccksankaufs eines ehemaligen Industriestandorts sollten die standortbezogenen Rahmenbedingungen gepr\u00fcft werden. Unsere Leistungen: Erarbeitung einer Desktop-Studie (\u201eQuick-Check\u201c) zur Pr\u00fcfung der standortbezogenen Rahmenbedingungen bzgl. Planungsrecht, Geotechnik, Altlasten, Kampfmittel, Natur- und Artenschutz, Ver- und Entsorgung, Verkehr und Schall; Beratung des Kunden in Hinblick auf notwendige weiterf\u00fchrende Untersuchungen (Geb\u00e4udeschadstoffuntersuchung, Baugrund- und Altlastenuntersuchung, Artenschutz-Potenzialanalyse und","og:url":"https:\/\/tucherundpartner.de\/en\/projects\/environmental-due-diligence-quick-check-fur-eine-flachenentwicklung-bei-hamburg\/","article:published_time":"2023-06-15T00:00:00+00:00","article:modified_time":"2023-06-15T00:00:00+00:00","twitter:card":"summary_large_image","twitter:title":"Environmental Due Diligence (\u201eQuick-Check\u201c) f\u00fcr eine Fl\u00e4chenentwicklung bei Hamburg - Tucher Ingenieure GmbH","twitter:description":"Projektbeschreibung: Im Rahmen eines geplanten Grundst\u00fccksankaufs eines ehemaligen Industriestandorts sollten die standortbezogenen Rahmenbedingungen gepr\u00fcft werden. Unsere Leistungen: Erarbeitung einer Desktop-Studie (\u201eQuick-Check\u201c) zur Pr\u00fcfung der standortbezogenen Rahmenbedingungen bzgl. Planungsrecht, Geotechnik, Altlasten, Kampfmittel, Natur- und Artenschutz, Ver- und Entsorgung, Verkehr und Schall; Beratung des Kunden in Hinblick auf notwendige weiterf\u00fchrende Untersuchungen (Geb\u00e4udeschadstoffuntersuchung, Baugrund- und Altlastenuntersuchung, Artenschutz-Potenzialanalyse und"},"aioseo_meta_data":{"post_id":"21084","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-10-29 08:00:09","updated":"2025-10-29 08:00:09","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/tucherundpartner.de\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/tucherundpartner.de\/en\/projects\/\" title=\"Projects\">Projects<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/tucherundpartner.de\/en\/project-category\/umwelt\/\" title=\"Umwelt\">Umwelt<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEnvironmental Due Diligence (\u201eQuick-Check\u201c) f\u00fcr eine Fl\u00e4chenentwicklung bei Hamburg\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/tucherundpartner.de\/en"},{"label":"Projects","link":"https:\/\/tucherundpartner.de\/en\/projects\/"},{"label":"Umwelt","link":"https:\/\/tucherundpartner.de\/en\/project-category\/umwelt\/"},{"label":"Environmental Due Diligence (\u201eQuick-Check\u201c) f\u00fcr eine Fl\u00e4chenentwicklung bei Hamburg","link":"https:\/\/tucherundpartner.de\/en\/projects\/environmental-due-diligence-quick-check-fur-eine-flachenentwicklung-bei-hamburg\/"}],"_links":{"self":[{"href":"https:\/\/tucherundpartner.de\/en\/wp-json\/wp\/v2\/projects\/21084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tucherundpartner.de\/en\/wp-json\/wp\/v2\/projects"}],"about":[{"href":"https:\/\/tucherundpartner.de\/en\/wp-json\/wp\/v2\/types\/projects"}],"author":[{"embeddable":true,"href":"https:\/\/tucherundpartner.de\/en\/wp-json\/wp\/v2\/users\/49"}],"wp:attachment":[{"href":"https:\/\/tucherundpartner.de\/en\/wp-json\/wp\/v2\/media?parent=21084"}],"wp:term":[{"taxonomy":"company-group","embeddable":true,"href":"https:\/\/tucherundpartner.de\/en\/wp-json\/wp\/v2\/company-group?post=21084"},{"taxonomy":"project-category","embeddable":true,"href":"https:\/\/tucherundpartner.de\/en\/wp-json\/wp\/v2\/project-category?post=21084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}